{"id":27159,"date":"2023-10-19T14:57:51","date_gmt":"2023-10-19T12:57:51","guid":{"rendered":"https:\/\/www.redbug-culture.com\/blog\/?p=27159"},"modified":"2024-11-28T13:26:06","modified_gmt":"2024-11-28T12:26:06","slug":"kleiner-vogel-glueck-von-martin-mandler","status":"publish","type":"post","link":"https:\/\/www.redbug-culture.com\/blog\/2023\/10\/kleiner-vogel-glueck-von-martin-mandler\/","title":{"rendered":"&#8222;Kleiner Vogel Gl\u00fcck&#8220; von Martin Mandler"},"content":{"rendered":"<h6>&#8222;Kleiner Vogel Gl\u00fcck&#8220; von Martin Mandler<\/h6>\n<p>Mit \u00bbKleiner Vogel Gl\u00fcck\u00ab hat Martin Mandler ein wunderbares, mutiges, ruhiges Buch geschrieben.<\/p>\n<p><a href=\"https:\/\/www.redbug-culture.com\/blog\/wp-content\/uploads\/2023\/10\/Kleiner-Vogel-Glueck.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-27160 alignright\" src=\"https:\/\/www.redbug-culture.com\/blog\/wp-content\/uploads\/2023\/10\/Kleiner-Vogel-Glueck-652x1024.jpg\" alt=\"Kleiner Vogel Gl\u00fcck von Martin Mandler\" width=\"352\" height=\"553\" srcset=\"https:\/\/www.redbug-culture.com\/blog\/wp-content\/uploads\/2023\/10\/Kleiner-Vogel-Glueck-652x1024.jpg 652w, https:\/\/www.redbug-culture.com\/blog\/wp-content\/uploads\/2023\/10\/Kleiner-Vogel-Glueck-191x300.jpg 191w, https:\/\/www.redbug-culture.com\/blog\/wp-content\/uploads\/2023\/10\/Kleiner-Vogel-Glueck-768x1206.jpg 768w, https:\/\/www.redbug-culture.com\/blog\/wp-content\/uploads\/2023\/10\/Kleiner-Vogel-Glueck.jpg 955w\" sizes=\"auto, (max-width: 352px) 100vw, 352px\" \/><\/a>Es spielt zu gro\u00dfen Teilen an der Dolomiten Front im Ersten Weltkrieg. Ein Buch \u00fcber den ersten Weltkrieg, in dem nur ein einziger Schuss f\u00e4llt. Konzentriert auf wenige Stunden, in denen uns ein souver\u00e4ner Erz\u00e4hler an den \u00dcberlegungen des Tiroler Bergbauernsohn Hans teilhaben l\u00e4sst. Der als Soldat in seinem Unterstand weit oben irgendwo in einer verschneiten Bergflanke liegt und \u00fcber die Absurdit\u00e4t des Krieges sinniert.<span class=\"Apple-converted-space\">\u00a0<\/span><\/p>\n<p>Dabei steigert sich die Spannung beinahe unmerklich, weil Hans einen immer gr\u00f6\u00dferen Drang versp\u00fcrt, an diesem sch\u00f6nen, ruhigen Tag, einmal aus dem Unterstand hinauszutreten und sich auf das weite Schneefeld in die Sonne zu legen. Vielleicht sogar bis zum Kamm aufzusteigen, um noch einmal ins Tal zu schauen, wohl wissend, dass er dabei sehr wahrscheinlich ins Sicht- und Schussfeld der Italiener geraten w\u00fcrde.<\/p>\n<p>Der \u00bbItaliener\u00ab, die vielleicht im Nachbardorf aufgewachsen sind. Deren Bewohnern er sich nicht nur n\u00e4her f\u00fchlt, als den \u00bbgro\u00dfkopferten Gener\u00e4len\u00ab, \u00bbdie nicht lange fackeln, wenn ein Befehl zu unterschreiben ist, der Zehntausende in den Tod schickt\u00ab, sondern mit denen ihn auch viel mehr verbindet als mit den Kameraden, die von irgendwoher, vielleicht aus D\u00fcsseldorf oder sonstwo in die Berge abkommandiert sind und jetzt neben ihm hoch oben im Gebirge im Sch\u00fctzengraben liegen.<\/p>\n<h6>Struktur der Erz\u00e4hlung<\/h6>\n<p>In die Haupterz\u00e4hlung sind neun zum Teil skurrile Geschichten eingestreut, die zu ganz unterschiedlichen Zeiten, an ganz verschiedenen Orten spielen. Nur zwei, wie sich sp\u00e4t herausstellt, sind eine Art Rahmenhandlung zur Hauptgeschichte. Wie kann das funktionieren? Eine sich so ruhig entwickelte Geschichte wie die von Hans in seinem Vorposten, weit au\u00dfen im Grabe, \u00a0immer wieder zu unterbrechen? Den Leser hinauszuwerfen aus Hans\u2019 Gedanken vor seinem in der Sonne leuchtenden Schneefeld in ganz andere Settings? Nach Brasilien 2016, auf einen Kirchturm ungef\u00e4hr im Jahr 2000, zu einem Kiffer 1997, einem Hobbyfotografen 2014 \u2026<\/p>\n<p>Damit es funktioniert, hat Martin Mandler eine souver\u00e4ne Erz\u00e4hlerstimme erfunden, die uns Leser:innen, wie eine alte Bekannte direkt anspricht. Die \u00a0mit Ironie und gleichzeitig gro\u00dfem Ernst, mit Distanz und dennoch empathischer N\u00e4he von Menschen erz\u00e4hlt. Und die beharrlich, manchmal ohne es zu merken, ein Ziel verfolgen und dabei hin und wieder vom Kleinen Vogel Gl\u00fcck aufgesucht werden.<\/p>\n<h6>Fazit<\/h6>\n<p>Unbedingte Leseempfehlung f\u00fcr alle, die gerne intensive und sprachlich gekonnte Texte lesen.<\/p>\n<h6>&#8222;Kleiner Vogel Gl\u00fcck&#8220;<\/h6>\n<ul>\n<li><a href=\"https:\/\/www.elsinor.de\">Elsinor Verlag<\/a><\/li>\n<li>ISBN 978-3-942788-77-9<\/li>\n<li>188 Seiten<\/li>\n<li>Klappenbroschur<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8222;Kleiner Vogel Gl\u00fcck&#8220; von Martin Mandler Mit \u00bbKleiner Vogel Gl\u00fcck\u00ab hat Martin Mandler ein wunderbares, mutiges, ruhiges Buch geschrieben. Es spielt zu gro\u00dfen Teilen an der Dolomiten Front im Ersten Weltkrieg. Ein Buch \u00fcber den ersten Weltkrieg, in dem nur ein einziger Schuss f\u00e4llt. Konzentriert auf wenige Stunden, in denen uns ein souver\u00e4ner Erz\u00e4hler an den \u00dcberlegungen des Tiroler Bergbauernsohn Hans teilhaben l\u00e4sst. Der als Soldat in seinem Unterstand weit oben irgendwo in einer verschneiten Bergflanke liegt und \u00fcber die Absurdit\u00e4t des Krieges sinniert.\u00a0 Dabei steigert sich die Spannung beinahe unmerklich, weil Hans einen immer gr\u00f6\u00dferen Drang versp\u00fcrt, an diesem sch\u00f6nen, ruhigen Tag, einmal aus dem Unterstand hinauszutreten und sich auf das weite Schneefeld in die Sonne zu legen. Vielleicht sogar bis zum Kamm aufzusteigen, um noch einmal ins Tal zu schauen, wohl wissend, dass er dabei sehr wahrscheinlich ins Sicht- und Schussfeld der Italiener geraten w\u00fcrde. Der \u00bbItaliener\u00ab, die vielleicht im Nachbardorf aufgewachsen sind. Deren Bewohnern er sich nicht nur n\u00e4her f\u00fchlt, als den \u00bbgro\u00dfkopferten Gener\u00e4len\u00ab, \u00bbdie nicht lange fackeln, wenn ein Befehl zu unterschreiben ist, der Zehntausende in den Tod schickt\u00ab, sondern mit denen ihn auch viel mehr verbindet als mit den Kameraden, die von irgendwoher, vielleicht aus [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":27154,"comment_status":"open","ping_status":"closed","sticky":false,"template":"single-fullwidth.php","format":"standard","meta":{"footnotes":"","_links_to":"","_links_to_target":""},"categories":[800],"tags":[542],"class_list":["post-27159","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rezension","tag-rezension"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&quot;Kleiner Vogel Gl\u00fcck&quot; von Martin Mandler - Red Bug Culture - Schreiben, Ver\u00f6ffentlichen, Kurse<\/title>\n<meta name=\"description\" content=\"&quot;Kleiner Vogel Gl\u00fcck&quot; von Martin Mandler -Mit \u00bbKleiner Vogel Gl\u00fcck\u00ab hat Martin Mandler ein wunderbares, mutiges, ruhiges Buch geschrieben.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.redbug-culture.com\/blog\/2023\/10\/kleiner-vogel-glueck-von-martin-mandler\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Kleiner Vogel Gl\u00fcck&quot; von Martin Mandler - Red Bug Culture - Schreiben, Ver\u00f6ffentlichen, Kurse\" \/>\n<meta property=\"og:description\" content=\"&quot;Kleiner Vogel Gl\u00fcck&quot; von Martin Mandler -Mit \u00bbKleiner Vogel Gl\u00fcck\u00ab hat Martin Mandler ein wunderbares, mutiges, ruhiges Buch geschrieben.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.redbug-culture.com\/blog\/2023\/10\/kleiner-vogel-glueck-von-martin-mandler\/\" \/>\n<meta property=\"og:site_name\" content=\"Red Bug Culture - Schreiben, Ver\u00f6ffentlichen, Kurse\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/RedBugBooks\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-19T12:57:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-28T12:26:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.redbug-culture.com\/blog\/wp-content\/uploads\/2023\/10\/banner-cult-tranpa_aaa_Rezension_9.png\" \/>\n\t<meta property=\"og:image:width\" content=\"740\" \/>\n\t<meta property=\"og:image:height\" content=\"493\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Uwe\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Uwe\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/2023\\\/10\\\/kleiner-vogel-glueck-von-martin-mandler\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/2023\\\/10\\\/kleiner-vogel-glueck-von-martin-mandler\\\/\"},\"author\":{\"name\":\"Uwe\",\"@id\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/#\\\/schema\\\/person\\\/8b267d63425e84abb5c33e3766015952\"},\"headline\":\"&#8222;Kleiner Vogel Gl\u00fcck&#8220; von Martin Mandler\",\"datePublished\":\"2023-10-19T12:57:51+00:00\",\"dateModified\":\"2024-11-28T12:26:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/2023\\\/10\\\/kleiner-vogel-glueck-von-martin-mandler\\\/\"},\"wordCount\":431,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/2023\\\/10\\\/kleiner-vogel-glueck-von-martin-mandler\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/banner-cult-tranpa_aaa_Rezension_9.png\",\"keywords\":[\"Rezension\"],\"articleSection\":[\"Rezension\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/2023\\\/10\\\/kleiner-vogel-glueck-von-martin-mandler\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/2023\\\/10\\\/kleiner-vogel-glueck-von-martin-mandler\\\/\",\"url\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/2023\\\/10\\\/kleiner-vogel-glueck-von-martin-mandler\\\/\",\"name\":\"\\\"Kleiner Vogel Gl\u00fcck\\\" von Martin Mandler - Red Bug Culture - Schreiben, Ver\u00f6ffentlichen, Kurse\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/2023\\\/10\\\/kleiner-vogel-glueck-von-martin-mandler\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/2023\\\/10\\\/kleiner-vogel-glueck-von-martin-mandler\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/banner-cult-tranpa_aaa_Rezension_9.png\",\"datePublished\":\"2023-10-19T12:57:51+00:00\",\"dateModified\":\"2024-11-28T12:26:06+00:00\",\"description\":\"\\\"Kleiner Vogel Gl\u00fcck\\\" von Martin Mandler -Mit \u00bbKleiner Vogel Gl\u00fcck\u00ab hat Martin Mandler ein wunderbares, mutiges, ruhiges Buch geschrieben.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/2023\\\/10\\\/kleiner-vogel-glueck-von-martin-mandler\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/2023\\\/10\\\/kleiner-vogel-glueck-von-martin-mandler\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/2023\\\/10\\\/kleiner-vogel-glueck-von-martin-mandler\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/banner-cult-tranpa_aaa_Rezension_9.png\",\"contentUrl\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/banner-cult-tranpa_aaa_Rezension_9.png\",\"width\":740,\"height\":493,\"caption\":\"Red Bug Culture Rezension\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/2023\\\/10\\\/kleiner-vogel-glueck-von-martin-mandler\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8222;Kleiner Vogel Gl\u00fcck&#8220; von Martin Mandler\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/\",\"name\":\"Red Bug Culture - Schreiben, Ver\u00f6ffentlichen, Kurse\",\"description\":\"Tipps &amp; Coaching f\u00fcr Autor:innen, Rezensionen\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/#organization\",\"name\":\"Red Bug Culture - Schreiben, Ver\u00f6ffentlichen, Kurse\",\"url\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/RBB_Culture-create-your-life_2.png\",\"contentUrl\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/wp-content\\\/uploads\\\/2026\\\/08\\\/RBB_Culture-create-your-life_2.png\",\"width\":780,\"height\":332,\"caption\":\"Red Bug Culture - Schreiben, Ver\u00f6ffentlichen, Kurse\"},\"image\":{\"@id\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/RedBugBooks\",\"https:\\\/\\\/www.instagram.com\\\/redbugbooks\\\/\",\"https:\\\/\\\/de.pinterest.com\\\/redbugbooks\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCOm3VgRiQqWfmWIUI60BUqQ?app=desktop\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/#\\\/schema\\\/person\\\/8b267d63425e84abb5c33e3766015952\",\"name\":\"Uwe\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ffe5e8a99554e8a798f9c3004929e8e65cd151b1a6379b7374e37960569a6d4e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ffe5e8a99554e8a798f9c3004929e8e65cd151b1a6379b7374e37960569a6d4e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/ffe5e8a99554e8a798f9c3004929e8e65cd151b1a6379b7374e37960569a6d4e?s=96&d=mm&r=g\",\"caption\":\"Uwe\"},\"sameAs\":[\"http:\\\/\\\/www.uwecarow.de\"],\"url\":\"https:\\\/\\\/www.redbug-culture.com\\\/blog\\\/author\\\/uwe\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Kleiner Vogel Gl\u00fcck\" von Martin Mandler - Red Bug Culture - Schreiben, Ver\u00f6ffentlichen, Kurse","description":"\"Kleiner Vogel Gl\u00fcck\" von Martin Mandler -Mit \u00bbKleiner Vogel Gl\u00fcck\u00ab hat Martin Mandler ein wunderbares, mutiges, ruhiges Buch geschrieben.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.redbug-culture.com\/blog\/2023\/10\/kleiner-vogel-glueck-von-martin-mandler\/","og_locale":"de_DE","og_type":"article","og_title":"\"Kleiner Vogel Gl\u00fcck\" von Martin Mandler - Red Bug Culture - Schreiben, Ver\u00f6ffentlichen, Kurse","og_description":"\"Kleiner Vogel Gl\u00fcck\" von Martin Mandler -Mit \u00bbKleiner Vogel Gl\u00fcck\u00ab hat Martin Mandler ein wunderbares, mutiges, ruhiges Buch geschrieben.","og_url":"https:\/\/www.redbug-culture.com\/blog\/2023\/10\/kleiner-vogel-glueck-von-martin-mandler\/","og_site_name":"Red Bug Culture - Schreiben, Ver\u00f6ffentlichen, Kurse","article_publisher":"https:\/\/www.facebook.com\/RedBugBooks","article_published_time":"2023-10-19T12:57:51+00:00","article_modified_time":"2024-11-28T12:26:06+00:00","og_image":[{"width":740,"height":493,"url":"https:\/\/www.redbug-culture.com\/blog\/wp-content\/uploads\/2023\/10\/banner-cult-tranpa_aaa_Rezension_9.png","type":"image\/png"}],"author":"Uwe","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Uwe","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.redbug-culture.com\/blog\/2023\/10\/kleiner-vogel-glueck-von-martin-mandler\/#article","isPartOf":{"@id":"https:\/\/www.redbug-culture.com\/blog\/2023\/10\/kleiner-vogel-glueck-von-martin-mandler\/"},"author":{"name":"Uwe","@id":"https:\/\/www.redbug-culture.com\/blog\/#\/schema\/person\/8b267d63425e84abb5c33e3766015952"},"headline":"&#8222;Kleiner Vogel Gl\u00fcck&#8220; von Martin Mandler","datePublished":"2023-10-19T12:57:51+00:00","dateModified":"2024-11-28T12:26:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.redbug-culture.com\/blog\/2023\/10\/kleiner-vogel-glueck-von-martin-mandler\/"},"wordCount":431,"commentCount":0,"publisher":{"@id":"https:\/\/www.redbug-culture.com\/blog\/#organization"},"image":{"@id":"https:\/\/www.redbug-culture.com\/blog\/2023\/10\/kleiner-vogel-glueck-von-martin-mandler\/#primaryimage"},"thumbnailUrl":"https:\/\/www.redbug-culture.com\/blog\/wp-content\/uploads\/2023\/10\/banner-cult-tranpa_aaa_Rezension_9.png","keywords":["Rezension"],"articleSection":["Rezension"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.redbug-culture.com\/blog\/2023\/10\/kleiner-vogel-glueck-von-martin-mandler\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.redbug-culture.com\/blog\/2023\/10\/kleiner-vogel-glueck-von-martin-mandler\/","url":"https:\/\/www.redbug-culture.com\/blog\/2023\/10\/kleiner-vogel-glueck-von-martin-mandler\/","name":"\"Kleiner Vogel Gl\u00fcck\" von Martin Mandler - Red Bug Culture - Schreiben, Ver\u00f6ffentlichen, Kurse","isPartOf":{"@id":"https:\/\/www.redbug-culture.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.redbug-culture.com\/blog\/2023\/10\/kleiner-vogel-glueck-von-martin-mandler\/#primaryimage"},"image":{"@id":"https:\/\/www.redbug-culture.com\/blog\/2023\/10\/kleiner-vogel-glueck-von-martin-mandler\/#primaryimage"},"thumbnailUrl":"https:\/\/www.redbug-culture.com\/blog\/wp-content\/uploads\/2023\/10\/banner-cult-tranpa_aaa_Rezension_9.png","datePublished":"2023-10-19T12:57:51+00:00","dateModified":"2024-11-28T12:26:06+00:00","description":"\"Kleiner Vogel Gl\u00fcck\" von Martin Mandler -Mit \u00bbKleiner Vogel Gl\u00fcck\u00ab hat Martin Mandler ein wunderbares, mutiges, ruhiges Buch geschrieben.","breadcrumb":{"@id":"https:\/\/www.redbug-culture.com\/blog\/2023\/10\/kleiner-vogel-glueck-von-martin-mandler\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.redbug-culture.com\/blog\/2023\/10\/kleiner-vogel-glueck-von-martin-mandler\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.redbug-culture.com\/blog\/2023\/10\/kleiner-vogel-glueck-von-martin-mandler\/#primaryimage","url":"https:\/\/www.redbug-culture.com\/blog\/wp-content\/uploads\/2023\/10\/banner-cult-tranpa_aaa_Rezension_9.png","contentUrl":"https:\/\/www.redbug-culture.com\/blog\/wp-content\/uploads\/2023\/10\/banner-cult-tranpa_aaa_Rezension_9.png","width":740,"height":493,"caption":"Red Bug Culture Rezension"},{"@type":"BreadcrumbList","@id":"https:\/\/www.redbug-culture.com\/blog\/2023\/10\/kleiner-vogel-glueck-von-martin-mandler\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.redbug-culture.com\/blog\/"},{"@type":"ListItem","position":2,"name":"&#8222;Kleiner Vogel Gl\u00fcck&#8220; von Martin Mandler"}]},{"@type":"WebSite","@id":"https:\/\/www.redbug-culture.com\/blog\/#website","url":"https:\/\/www.redbug-culture.com\/blog\/","name":"Red Bug Culture - Schreiben, Ver\u00f6ffentlichen, Kurse","description":"Tipps &amp; Coaching f\u00fcr Autor:innen, Rezensionen","publisher":{"@id":"https:\/\/www.redbug-culture.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.redbug-culture.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/www.redbug-culture.com\/blog\/#organization","name":"Red Bug Culture - Schreiben, Ver\u00f6ffentlichen, Kurse","url":"https:\/\/www.redbug-culture.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.redbug-culture.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.redbug-culture.com\/blog\/wp-content\/uploads\/2026\/08\/RBB_Culture-create-your-life_2.png","contentUrl":"https:\/\/www.redbug-culture.com\/blog\/wp-content\/uploads\/2026\/08\/RBB_Culture-create-your-life_2.png","width":780,"height":332,"caption":"Red Bug Culture - Schreiben, Ver\u00f6ffentlichen, Kurse"},"image":{"@id":"https:\/\/www.redbug-culture.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/RedBugBooks","https:\/\/www.instagram.com\/redbugbooks\/","https:\/\/de.pinterest.com\/redbugbooks\/","https:\/\/www.youtube.com\/channel\/UCOm3VgRiQqWfmWIUI60BUqQ?app=desktop"]},{"@type":"Person","@id":"https:\/\/www.redbug-culture.com\/blog\/#\/schema\/person\/8b267d63425e84abb5c33e3766015952","name":"Uwe","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/ffe5e8a99554e8a798f9c3004929e8e65cd151b1a6379b7374e37960569a6d4e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/ffe5e8a99554e8a798f9c3004929e8e65cd151b1a6379b7374e37960569a6d4e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ffe5e8a99554e8a798f9c3004929e8e65cd151b1a6379b7374e37960569a6d4e?s=96&d=mm&r=g","caption":"Uwe"},"sameAs":["http:\/\/www.uwecarow.de"],"url":"https:\/\/www.redbug-culture.com\/blog\/author\/uwe\/"}]}},"_links":{"self":[{"href":"https:\/\/www.redbug-culture.com\/blog\/wp-json\/wp\/v2\/posts\/27159","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.redbug-culture.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.redbug-culture.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.redbug-culture.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.redbug-culture.com\/blog\/wp-json\/wp\/v2\/comments?post=27159"}],"version-history":[{"count":0,"href":"https:\/\/www.redbug-culture.com\/blog\/wp-json\/wp\/v2\/posts\/27159\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.redbug-culture.com\/blog\/wp-json\/wp\/v2\/media\/27154"}],"wp:attachment":[{"href":"https:\/\/www.redbug-culture.com\/blog\/wp-json\/wp\/v2\/media?parent=27159"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.redbug-culture.com\/blog\/wp-json\/wp\/v2\/categories?post=27159"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.redbug-culture.com\/blog\/wp-json\/wp\/v2\/tags?post=27159"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}